{"id":65615,"date":"2024-07-25T12:31:12","date_gmt":"2024-07-25T16:31:12","guid":{"rendered":"https:\/\/elsurti.com\/?post_type=chequeo&#038;p=65615"},"modified":"2024-07-26T11:54:00","modified_gmt":"2024-07-26T15:54:00","slug":"oficialismo-avanza-ley-contra-las-organizaciones-en-paraguay","status":"publish","type":"chequeo","link":"https:\/\/elsurti.com\/pt\/laprecisa\/chequeo\/2024\/07\/25\/oficialismo-avanza-ley-contra-las-organizaciones-en-paraguay\/","title":{"rendered":"Oficialismo en Paraguay impulsa una ley contra organizaciones"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Un proyecto de ley que de forma nominal busca aumentar el control y la rendici\u00f3n de cuentas de organizaciones sin fines de lucro amenaza el derecho a la libre asociaci\u00f3n.<\/li>\n\n\n\n<li>Defensores de derechos humanos, representantes de comisiones vecinales y organizaciones internacionales como Amnist\u00eda se han posicionado en contra de la iniciativa, a la que califican de <em>ley garrote<\/em> por abrir la puerta a la persecuci\u00f3n. Tambi\u00e9n manifestaron preocupaci\u00f3n juristas y hasta el representante de la Iglesia Cat\u00f3lica.<\/li>\n\n\n\n<li>Tres relatoras de la ONU hicieron un llamamiento al presidente Santiago Pe\u00f1a a evaluar el proyecto. Se\u00f1alan que podr\u00eda restringir de forma indebida los derechos a la privacidad, la libertad de expresi\u00f3n y de asociaci\u00f3n pac\u00edfica.<\/li>\n\n\n\n<li>El proyecto es una iniciativa del oficialismo, representado por el Partido Colorado y af\u00edn al expresidente Horacio Cartes.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-drop-cap\">La C\u00e1mara de Senadores aprob\u00f3 el 8 de julio el <a href=\"https:\/\/silpy.congreso.gov.py\/web\/expediente\/130058\" data-type=\"link\" data-id=\"https:\/\/silpy.congreso.gov.py\/web\/expediente\/130058\">proyecto de ley<\/a> \u201cque establece el control, la transparencia y la rendici\u00f3n de cuentas de las organizaciones sin fines de lucro (OSFL)\u201d que administren fondos p\u00fablicos o privados de origen nacional e internacional. La iniciativa pas\u00f3 a Diputados, donde el oficialismo, impulsor de la normativa, tambi\u00e9n tiene mayor\u00eda para sancionar la ley.\u00a0<\/p>\n\n\n\n<p>El proyecto es de varios senadores colorados, entre ellos Gustavo Leite, Basilio N\u00fa\u00f1ez y Lizarella Valiente, que responden al movimiento del exmandatario Horacio Cartes \u2015hoy presidente del Partido Colorado\u2015 que apadrin\u00f3 a Santiago Pe\u00f1a. Se caracterizan por su discurso <em>anti globalista<\/em> e impulsar proyectos en esa l\u00ednea, como la <a href=\"https:\/\/www.abc.com.py\/politica\/2023\/11\/01\/confirman-reculada-cartista-y-se-mantiene-convenio-con-la-union-europea\/\">derogaci\u00f3n de un financiamiento de la Uni\u00f3n Europea<\/a> para la educaci\u00f3n por temor a la \u201cideolog\u00eda de g\u00e9nero\u201d.&nbsp;<\/p>\n\n\n\n<p>Conocida como \u201cley garrote\u201d por el riesgo de que el cartismo la use contra sus cr\u00edticos, la iniciativa afecta a una diversidad de organizaciones: desde asociaciones de vecinos hasta organismos internacionales, incluyendo \u201ccualquier persona f\u00edsica o jur\u00eddica\u201d. Crea un registro obligatorio a cargo del Ministerio de Econom\u00eda y Finanzas en el que las OSFL deben inscribirse, detallando fuentes de financiamiento, lista de contratados y otros requerimientos exhaustivos.&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n obliga a las organizaciones a presentar un informe semestral al Ministerio de Econom\u00eda sobre el uso de los fondos y establece que no podr\u00e1n alegar cl\u00e1usulas de confidencialidad para eludir esta obligaci\u00f3n. En el caso de las OSFL que trabajan con alguna instituci\u00f3n del Estado, deber\u00e1n incluir los fondos en el presupuesto p\u00fablico.<\/p>\n\n\n\n<p>En cuanto a las sanciones por incumplir la ley, las organizaciones pueden ser castigadas con multas de hasta mil salarios m\u00ednimos (unos 370 mil d\u00f3lares) e incluso el cierre. Para los directivos, administradores o representantes, la multa m\u00e1xima es de 500 salarios m\u00ednimos (185 mil d\u00f3lares), adem\u00e1s de quedar inhabilitados para ocupar cargos similares en otras OSFL y en el sector p\u00fablico de cinco a diez a\u00f1os. Estas sanciones tambi\u00e9n se aplicar\u00e1n a cualquier persona f\u00edsica o jur\u00eddica \u201cque tuviera incidencia en la actividad\u201d de la organizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Organizaciones de la sociedad civil cuestionan el car\u00e1cter inconstitucional del proyecto por atentar contra varias garant\u00edas establecidas en la Carta Magna, como el derecho a la libre asociaci\u00f3n. En el mismo sentido, <a href=\"https:\/\/amnesty.org.py\/wp-content\/uploads\/2024\/07\/Briefing-AIPy-sobre-proyecto-de-ley-de-control-a-Ongs-vf.pdf\">Amnist\u00eda Internacional Paraguay se ha pronunciado<\/a>, advirtiendo sobre la tendencia regional de cierre del espacio c\u00edvico con este tipo de leyes, que buscan restringir la financiaci\u00f3n de las organizaciones, sobre todo la internacional, conden\u00e1ndolas a la desaparici\u00f3n. Esto se observa en <a href=\"https:\/\/www.dw.com\/es\/gobierno-de-nicaragua-cierra-otras-15-ong-y-traspasa-sus-bienes-al-estado\/a-69338611\">Nicaragua, donde van m\u00e1s de 3.600 ONG cerradas<\/a> desde 2018, mientras Venezuela avanza su propia versi\u00f3n con la denominada <a href=\"https:\/\/efectococuyo.com\/politica\/an-2020-sanciona-solo-nueve-articulos-ley-fiscalizar-ong\/\">Ley Antisociedad<\/a> y <a href=\"https:\/\/elpais.com\/planeta-futuro\/red-de-expertos\/2024-06-11\/el-control-a-las-ong-en-peru-un-zarpazo-a-la-democracia.html\">Per\u00fa discute otra iniciativa<\/a> del mismo corte.<\/p>\n\n\n\n<p>Por su parte, la <a href=\"https:\/\/spcommreports.ohchr.org\/TMResultsBase\/DownLoadPublicCommunicationFile?gId=29221\">declaraci\u00f3n conjunta de tres relatoras de la ONU<\/a> se\u00f1ala que el proyecto de ley podr\u00eda restringir indebidamente los derechos a la privacidad, la libertad de expresi\u00f3n y la libertad de reuni\u00f3n pac\u00edfica, adem\u00e1s de la libertad de asociaci\u00f3n, protegidos en el Pacto Internacional sobre Derechos Civiles y Pol\u00edticos, un tratado ratificado por Paraguay.<\/p>\n\n\n\n<p>Advierten que la definici\u00f3n amplia y vaga de una OSFL en el proyecto \u2015el alcance sobre cualquier organizaci\u00f3n que trabaje en el \u00e1mbito de \u201cprestaciones de exclusiva competencia del Estado\u201d, \u201cbien com\u00fan\u201d, \u201cutilidad p\u00fablica\u201d\u2015 podr\u00eda habilitar la aplicaci\u00f3n discrecional de la ley. Tambi\u00e9n que las sanciones son desproporcionadas y que esto podr\u00eda habilitar un r\u00e9gimen de persecuci\u00f3n de organizaciones.<\/p>\n\n\n\n<p>Pero no solo las organizaciones se han pronunciado sobre el proyecto. La Procuradur\u00eda recomend\u00f3 a los legisladores excluir a las organizaciones que administren fondos privados, as\u00ed como a los organismos y organizaciones internacionales. Tambi\u00e9n sugiri\u00f3 atenuar las sanciones, entre otras observaciones, como evitar la duplicaci\u00f3n de funciones y registros.<\/p>\n\n\n\n<p>Una organizaci\u00f3n que gestiona fondos privados ya cumple con una serie de obligaciones ante el Estado, que incluye a Tributaci\u00f3n, la Secretar\u00eda de Prevenci\u00f3n de Lavado de Dinero (Seprelad), el Ministerio del Trabajo y el Instituto de Previsi\u00f3n Social (IPS). Mientras que aquellas que administran fondos p\u00fablicos est\u00e1n sujetas a regulaciones espec\u00edficas. Por ejemplo, las transferencias est\u00e1n en los presupuestos de las instituciones y las organizaciones deben rendir cuentas semestralmente sobre el uso. Si no lo hacen, el Estado deja de transferir. Esta informaci\u00f3n est\u00e1 p\u00fablica en el sitio Web del Ministerio de Econom\u00eda.<\/p>\n\n\n\n<p>Esto contrasta con el discurso del oficialismo, que acusa a las organizaciones de no querer la transparencia. Apuntan a una supuesta \u201cagenda\u201d que oculta una injerencia extranjera a trav\u00e9s de los fondos que reciben las OSFL. Durante la aprobaci\u00f3n del proyecto en el Senado, los cartistas perfilaron a pol\u00edticos opositores, periodistas, activistas y organizaciones, vincul\u00e1ndolos al globalismo. En la sesi\u00f3n, mostraron videos conspiranoicos que viralizaron cuentas afines, exponiendo una supuesta trama que termin\u00f3 con la menci\u00f3n de George Soros. Tambi\u00e9n expusieron <a href=\"https:\/\/elsurti.com\/pt\/oligarquia\/reportaje\/2024\/07\/11\/pyragues-infiltran-reunion-privada-de-organizaciones\/\">sus pr\u00e1cticas de espionaje<\/a> al exhibir una reuni\u00f3n privada v\u00eda Zoom que hicieron representantes de la sociedad civil.&nbsp;<\/p>\n\n\n\n<p>Las campa\u00f1as del oficialismo contra algunas organizaciones y sus referentes, tambi\u00e9n contra medios y periodistas, son reforzadas por los medios de comunicaci\u00f3n de la familia del expresidente Cartes, as\u00ed como por sus ej\u00e9rcitos de trolls en las redes sociales. La arremetida se intensific\u00f3 luego de una serie de esc\u00e1ndalos de nepotismo que salpicaron incluso al vicepresidente de la Rep\u00fablica.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Texto: Romina C\u00e1ceres - Edici\u00f3n: Jazm\u00edn Acu\u00f1a<\/pre>","protected":false},"excerpt":{"rendered":"<p>El proyecto aprobado en el Senado extiende el control estatal sobre organizaciones sin fines de lucro que gestionan fondos privados de origen nacional y extranjero.<\/p>","protected":false},"author":5,"featured_media":65611,"template":"","tags":[23],"fenomeno":[167],"tema":[64],"legacy_site":[],"class_list":["post-65615","chequeo","type-chequeo","status-publish","has-post-thumbnail","hentry","tag-la-precisa","fenomeno-laprecisa","tema-cartismo","pmpro-has-access"],"acf":[],"_links":{"self":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/chequeo\/65615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/chequeo"}],"about":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/types\/chequeo"}],"author":[{"embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":11,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/chequeo\/65615\/revisions"}],"predecessor-version":[{"id":65630,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/chequeo\/65615\/revisions\/65630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/media\/65611"}],"wp:attachment":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/media?parent=65615"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/tags?post=65615"},{"taxonomy":"fenomeno","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/fenomeno?post=65615"},{"taxonomy":"tema","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/tema?post=65615"},{"taxonomy":"legacy_site","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/legacy_site?post=65615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}