{"id":9061,"date":"2020-11-13T15:17:04","date_gmt":"2020-11-13T19:17:04","guid":{"rendered":"https:\/\/elsurti.com\/?post_type=reportaje&#038;p=9061"},"modified":"2021-10-10T15:46:38","modified_gmt":"2021-10-10T19:46:38","slug":"mas-de-100-proveedoras-del-estado-accionaron-contra-declarar-sus-bienes","status":"publish","type":"reportaje","link":"https:\/\/elsurti.com\/pt\/oligarquia\/reportaje\/2020\/11\/13\/mas-de-100-proveedoras-del-estado-accionaron-contra-declarar-sus-bienes\/","title":{"rendered":"M\u00e1s de 100 proveedoras del Estado accionaron contra declarar sus bienes"},"content":{"rendered":"<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-lg-5\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-lg-7\">\n\t\t\t\n\n<p>M\u00e1s de 100 empresas promovieron acciones de inconstitucionalidad entre mayo y julio de 2020 contra la ley 6355\/19 que obliga a accionistas y directivos de contratistas del Estado a presentar declaraci\u00f3n jurada de bienes y rentas ante la Contralor\u00eda. Esta obligaci\u00f3n, que solo afectaba a funcionarios p\u00fablicos, es tambi\u00e9n hoy requisito para que el sector privado participe de contratos p\u00fablicos. Como primera medida, la Sala Constitucional de la Corte suspendi\u00f3 los efectos de la ley para estas proveedoras hasta que resuelva las acciones de inconstitucionalidad. Esto permite a esas empresas seguir present\u00e1ndose a las licitaciones.<\/p>\n\n\n\n<p>El argumento de las empresas para atacar de inconstitucional esta ley es que el art\u00edculo 104 de la Constituci\u00f3n establece que los sujetos obligados a declarar sus bienes y rentas son los funcionarios, empleados p\u00fablicos y, en general, quienes perciban remuneraciones del Estado. Uno de los directivos de la Uni\u00f3n Industrial Paraguaya (UIP), Jorge Pappalardo, hab\u00eda dicho que la ley era \u00ab<a href=\"https:\/\/www.ultimahora.com\/urgen-suspender-ley-que-exige-ddjj-vender-al-estado-n2884290.html\">absolutamente inconstitucional<\/a>\u00bb y que pondr\u00eda m\u00e1s trabas a los procesos de compras p\u00fablicas antes que transparentar.<\/p>\n\n\n\n<p>La ley 6355 ampl\u00eda esa obligaci\u00f3n a personas f\u00edsicas y jur\u00eddicas contratistas, concesionarias, asociaciones y fundaciones que reciben fondos p\u00fablicos, alg\u00fan tipo de contraprestaci\u00f3n o est\u00e9n vinculadas con el Estado bajo cualquier modalidad. Los afectados deben presentar su declaraci\u00f3n jurada de bienes y rentas a la Contralor\u00eda dentro de los 15 d\u00edas de concretarse la vinculaci\u00f3n con la actividad estatal o de recibir fondos p\u00fablicos, y en igual t\u00e9rmino al finalizar. En la pr\u00e1ctica, una proveedora debe hacer su declaraci\u00f3n cuando se presenta a una licitaci\u00f3n, cuando se le adjudica el contrato y al finalizar el mismo.<\/p>\n\n\n\n<p>Las declaraciones juradas de las proveedoras no son de acceso p\u00fablico, excepto las de aquellas que fueron adjudicadas en el marco de la ley de emergencia por la pandemia, que est\u00e1n publicadas en la p\u00e1gina de <a href=\"https:\/\/www.contraloria.gov.py\/index.php\/actividades-de-control\/declaracion-jurada-de-bienes-publicadas\">Contralor\u00eda<\/a>. Solo se puede acceder a esa informaci\u00f3n mediante orden judicial, tal como ocurri\u00f3 cuando la Corte fall\u00f3 a favor de la publicidad de las declaraciones de funcionarios p\u00fablicos desde 1992 hasta el 17 de junio de 2020. Gracias a ese hist\u00f3rico fallo, esa informaci\u00f3n hoy es p\u00fablica en la web de Contralor\u00eda.<\/p>\n\n\n\n<p>A trav\u00e9s de un pedido de informaci\u00f3n p\u00fablica, El Surtidor accedi\u00f3 a m\u00e1s de 160 resoluciones de mayo a julio 2020 de la Sala Constitucional que suspenden los efectos de la ley 6355 para la misma cantidad de proveedoras que accionaron en contra. Ponemos a disposici\u00f3n informaci\u00f3n preliminar de 30 de esas empresas en este <a href=\"https:\/\/elsurti.com\/pt\/oligarquia\/poder-real\/especial\/secreto-en-la-patria-contratista\/\">registro<\/a>, que actualizaremos de forma continua. Como parte de esa iniciativa, aqu\u00ed detallamos algunas de las contratistas que fueron beneficiadas con las suspensiones y sus adjudicaciones de 2010 a julio 2020 seg\u00fan informaci\u00f3n disponible en Contrataciones P\u00fablicas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Las farmac\u00e9uticas y proveedoras de insumos m\u00e9dicos que no quieren rendir cuentas<\/h3>\n\n\n\n<p>El grupo empresarial de la familia Scavone es uno de los mayores proveedores del Estado en el rubro farmac\u00e9utico. Los propietarios de tres de sus empresas accionaron contra la ley 6355 para no presentar declaraciones juradas: Vicente Scavone y CIA SAE (Laboratorios Lasca), Laboratorios de Productos \u00c9ticos CEISA y Scavone Hermanos SA (Laboratorios Catedral). La suma de los contratos p\u00fablicos de estas tres firmas en la \u00faltima d\u00e9cada supera los 2,3 billones de guaran\u00edes, unos 334 millones de d\u00f3lares al cambio actual. Uno de los principales accionistas, \u00d3scar Vicente Scavone, fue asesor econ\u00f3mico del expresidente Horacio Cartes y presidi\u00f3 el Club Olimpia.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"666\" src=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo4.jpg\" alt=\"\" class=\"wp-image-9069\" srcset=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo4.jpg 850w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo4-300x235.jpg 300w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo4-768x602.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure><\/div>\n\n\n\n<p>Distribuidora La Policl\u00ednica SA tambi\u00e9n accion\u00f3 contra las declaraciones juradas. La empresa vinculada a Norman Harrison Paleari es otra de las contratistas con mayores montos adjudicados desde 2010, con m\u00e1s de 764 mil millones de guaran\u00edes (USD 109 millones) en contratos. El empresario tambi\u00e9n es presidente de Aseguradora Yacyret\u00e1 y la Megacadena de Comunicaci\u00f3n, medio que igualmente accion\u00f3 contra la ley 6355. Es hermano del presidente de la Asociaci\u00f3n Paraguaya de F\u00fatbol (APF), Robert Harrison.<\/p>\n\n\n\n<p>Las proveedoras de equipos e insumos m\u00e9dicos que accionaron contra la ley tampoco tendr\u00e1n que declarar bienes. Una de ellas es Casa Boller, del exsenador liberal Rodrigo Campos Cervera, empresa que figura entre las diez mayores proveedoras del Estado con G. 1,4 billones en contratos desde 2010 (USD 205 millones). Otra es Index SACI de Ernesto Gerardo Wasmosy Monti, hermano del expresidente Juan Carlos Wasmosy, con adjudicaciones que totalizan los 202 millones de d\u00f3lares en el mismo periodo. La firma tambi\u00e9n est\u00e1 entre las diez mayores proveedoras.<\/p>\n\n\n\n<p>Asismed SA, principal proveedora de seguro m\u00e9dico para funcionarios p\u00fablicos, tambi\u00e9n present\u00f3 acci\u00f3n de inconstitucionalidad contra la ley. Esta empresa obtuvo contratos con el Estado por 1,2 billones de guaran\u00edes (USD 168 millones) desde 2010. Como representantes legales figuran Ricardo Doria Cortes, Ursula Filgueira, Ram\u00f3n Doria Cortes, Jorge Solano y Miguel Figueredo Caniza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Las grandes constructoras que est\u00e1n en contra de declarar sus bienes<\/h3>\n\n\n\n<p>El expresidente Juan Carlos Wasmosy no tendr\u00e1 que presentar su declaraci\u00f3n jurada de bienes y rentas como propietario de la Empresa Constructora Minera Paraguaya SA (Ecomipa). La Sala Constitucional hizo lugar a la inconstitucionalidad que present\u00f3 contra la ley 6355. Ecomipa obtuvo contratos p\u00fablicos por valor de G. 1,3 billones (USD 181 millones) en la \u00faltima d\u00e9cada, sin contar los consorcios que integra con otras empresas. Seg\u00fan el diario \u00daltima Hora, la constructora de Wasmosy fue <a href=\"https:\/\/www.ultimahora.com\/firma-wasmosy-la-mas-beneficiada-obras-del-mopc-la-era-cartes-n2701196.html\">la m\u00e1s beneficiada con adjudicaciones del MOPC<\/a> durante el gobierno de Horacio Cartes.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"850\" height=\"666\" src=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo5.jpg\" alt=\"\" class=\"wp-image-9070\" srcset=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo5.jpg 850w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo5-300x235.jpg 300w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo5-768x602.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure><\/div>\n\n\n\n<p>Benito Roggio e Hijos SA es otra de las principales contratistas del Estado en el rubro de la construcci\u00f3n que fue beneficiada con la suspensi\u00f3n de la ley 6355. La acci\u00f3n fue promovida por Emilio Gill Insfr\u00e1n, Gustavo Armando Pavetti Ibarrola y \u00d3scar Alberto Franco Vel\u00e1zquez. La empresa integra el Consorcio D-R Costanera junto a CDD Construcciones, encargada del Corredor Vial Bot\u00e1nico. Los contratos p\u00fablicos de la firma \u2013parte del Grupo Roggio de Argentina\u2013 superan 1 bill\u00f3n de guaran\u00edes (USD 160 millones), sin incluir las adjudicaciones de los consorcios que integra.<\/p>\n\n\n\n<p>La empresa Ingenier\u00eda de Topograf\u00eda y Caminos SA (T&amp;C SA) de Francisco Gri\u00f1\u00f3 Guill\u00e9n tampoco tendr\u00e1 que rendir cuentas, pese a que es una de las principales contratistas del rubro. Sus adjudicaciones en la \u00faltima d\u00e9cada suman 1 bill\u00f3n de guaran\u00edes (USD 147 millones), sin incluir los consorcios. Una de las obras que tiene en ejecuci\u00f3n es la Costanera Sur, como parte del Consorcio del Sur junto a la espa\u00f1ola Eurofinsa SA.<\/p>\n\n\n\n<p>La Sala Constitucional tambi\u00e9n hizo lugar a la acci\u00f3n contra las declaraciones juradas promovida por Tecnoedil SA Constructora, entre cuyos accionistas figura Paul Emile Sarubbi Corina, hijo de Paul Sarubbi, director de Yacyret\u00e1 en el gobierno de Nicanor Duarte Frutos. Esta empresa obtuvo contratos por 962 mil millones (USD 137 millones) en los \u00faltimos diez a\u00f1os, sin contar las adjudicaciones por consorcios. Otra constructora vinculada a un ex funcionario que obtuvo la suspensi\u00f3n de la ley 6355 es Jim\u00e9nez Gaona y Lima Empresas de Construcciones SA, la empresa de la familia de Ram\u00f3n Jim\u00e9nez Gaona, exministro de Obras P\u00fablicas durante el gobierno de Cartes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Medios de comunicaci\u00f3n tambi\u00e9n accionaron contra la transparencia<\/h3>\n\n\n\n<p>La principal proveedora de servicios m\u00f3viles del pa\u00eds, Telef\u00f3nica Celular del Paraguay SAE (Telecel SAE), cuya marca comercial es Tigo, accion\u00f3 contra la ley de declaraciones juradas. La subsidiaria del Grupo Millicom International tiene contratos con varias instituciones del Estado por m\u00e1s de G. 87 mil millones, unos 12 millones de d\u00f3lares. Otras empresas del grupo que atacaron de inconstitucional la ley son Servicios y Productos Multimedios SA (SPM), el canal Teledeportes Paraguay SA, Mobile Cash SA y Lothar Systems SA (Lothar).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"850\" height=\"666\" src=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo6.jpg\" alt=\"\" class=\"wp-image-9071\" srcset=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo6.jpg 850w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo6-300x235.jpg 300w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo6-768x602.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure><\/div>\n\n\n\n<p>Empresas del sector de artes gr\u00e1ficas tambi\u00e9n consiguieron la medida cautelar para que sus due\u00f1os no declaren sus bienes. Una de ellas es Mercurio SA de la familia Zuccolillo, que es propietaria del diario Abc Color. Las adjudicaciones de la imprenta rondan los G. 93 mil millones (USD 13 millones). La otra es Artes Gr\u00e1ficas Zamphiropolos SA, que tiene contratos con varias instituciones p\u00fablicas por G. 157 mil millones (USD 22 millones). Patricia Eulerich Zamphiropolos, una de las accionantes de la empresa, es esposa del exministro de Hacienda, Benigno L\u00f3pez.<\/p>\n\n\n\n<p>Entre los medios de comunicaci\u00f3n que accionaron para no declarar bienes est\u00e1n Televisi\u00f3n Cerro Cor\u00e1 SA (Canal 9), Paravisi\u00f3n, Televisora del Este (PTV) y Televisora Itap\u00faa (Sur), todos del Grupo Albavisi\u00f3n. Como directivo de los dos primeros canales figura Marcelo Fleitas Portaluppi, mientras que el representante legal de los canales del Este e Itap\u00faa es Ismael Hadid Florent\u00edn. En total, en la \u00faltima d\u00e9cada estas empresas obtuvieron juntas m\u00e1s G. 10 mil millones en contratos con el Estado, casi 1 mill\u00f3n y medio de d\u00f3lares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La trazabilidad del dinero p\u00fablico en disputa<\/h3>\n\n\n\n<p>El director de Declaraciones Juradas de la Contralor\u00eda, Armindo Torres, dijo que unas 3.000 empresas proveedoras presentaron sus declaraciones juradas en lo que va de 2020 en cumplimiento de la ley 6355. Sostuvo que la aplicaci\u00f3n de esta ley no es f\u00e1cil, en primer lugar porque no tienen los recursos suficientes para verificar tanto las declaraciones juradas de funcionarios p\u00fablicos como las de empresas. Sobre la avalancha de acciones ante la Corte, record\u00f3 que la Contralor\u00eda hab\u00eda advertido en dict\u00e1menes que la ley \u00abrozaba la inconstitucionalidad\u00bb al considerar el art\u00edculo 104 de la Constituci\u00f3n que establece que los funcionarios p\u00fablicos deben presentar la declaraci\u00f3n jurada.&nbsp;<\/p>\n\n\n\n<p>\u00abPero hoy la ley est\u00e1 vigente y se tiene que cumplir\u00bb, enfatiza Torres.&nbsp;<\/p>\n\n\n\n<p>En opini\u00f3n del abogado Federico Legal, del Instituto de Derecho y Econom\u00eda Ambiental (IDEA), un segundo criterio que se debe considerar al interpretar esta ley es el control de la trazabilidad del dinero p\u00fablico: \u00abEn ese sentido, conocer las declaraciones juradas de proveedoras va a contribuir a prevenir posibles conflictos de intereses. Lo que s\u00ed se tiene que diferenciar es que una empresa, por m\u00e1s que reciba dinero p\u00fablico, no tiene las mismas obligaciones que un funcionario\u00bb.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"666\" src=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo7.jpg\" alt=\"\" class=\"wp-image-9072\" srcset=\"https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo7.jpg 850w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo7-300x235.jpg 300w, https:\/\/elsurti.com\/wp-content\/uploads\/2020\/11\/801_DDJJ-articulo7-768x602.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure><\/div>\n\n\t<\/div>\n\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Una ley obliga a empresas proveedoras del Estado a presentar sus declaraciones juradas. La justicia les benefici\u00f3 con la suspensi\u00f3n de los efectos de esa ley.<\/p>","protected":false},"author":5,"featured_media":9062,"template":"single-reportaje-derecha.php","tags":[60],"fenomeno":[42],"tema":[61],"legacy_site":[],"class_list":["post-9061","reportaje","type-reportaje","status-publish","has-post-thumbnail","hentry","tag-poder-real","fenomeno-oligarquia","tema-poder-real","pmpro-has-access"],"acf":[],"_links":{"self":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/reportaje\/9061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/reportaje"}],"about":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/types\/reportaje"}],"author":[{"embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":7,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/reportaje\/9061\/revisions"}],"predecessor-version":[{"id":9403,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/reportaje\/9061\/revisions\/9403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/media\/9062"}],"wp:attachment":[{"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/media?parent=9061"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/tags?post=9061"},{"taxonomy":"fenomeno","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/fenomeno?post=9061"},{"taxonomy":"tema","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/tema?post=9061"},{"taxonomy":"legacy_site","embeddable":true,"href":"https:\/\/elsurti.com\/pt\/wp-json\/wp\/v2\/legacy_site?post=9061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}